{"id":12040,"date":"2024-06-17T17:18:32","date_gmt":"2024-06-17T15:18:32","guid":{"rendered":"https:\/\/www.begrafenissenhaerens.be\/?p=12040"},"modified":"2024-06-17T17:18:32","modified_gmt":"2024-06-17T15:18:32","slug":"mevr-martha-verkinderen","status":"publish","type":"post","link":"https:\/\/www.begrafenissenhaerens.be\/fr\/online-condoleren\/mevr-martha-verkinderen\/","title":{"rendered":"Mevr. Martha Verkinderen"},"content":{"rendered":"<p>Geboren te Meulebeke op 26 augustus 1934<br \/>\nen overleden in het WZC \u2018de Lichtervelde\u2019 te Eke op 14 juni 2024.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Geboren te Meulebeke op 26 augustus 1934 en overleden in het WZC \u2018de Lichtervelde\u2019 te Eke op 14 juni 2024.<\/p>\n","protected":false},"author":3,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"_acf_changed":false,"footnotes":""},"categories":[],"tags":[],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Mevr. Martha Verkinderen - HAERENS Sint-Martens-Latem<\/title>\n<meta name=\"robots\" content=\"noindex, follow\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Mevr. Martha Verkinderen - HAERENS Sint-Martens-Latem\" \/>\n<meta property=\"og:description\" content=\"Geboren te Meulebeke op 26 augustus 1934 en overleden in het WZC \u2018de Lichtervelde\u2019 te Eke op 14 juni 2024.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.begrafenissenhaerens.be\/fr\/online-condoleren\/mevr-martha-verkinderen\/\" \/>\n<meta property=\"og:site_name\" content=\"HAERENS Sint-Martens-Latem\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/BegrafenissenHaerens\/\" \/>\n<meta property=\"article:published_time\" content=\"2024-06-17T15:18:32+00:00\" \/>\n<meta name=\"author\" content=\"Evelyne Haerens\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"Evelyne Haerens\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/www.begrafenissenhaerens.be\/fr\/online-condoleren\/mevr-martha-verkinderen\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/www.begrafenissenhaerens.be\/fr\/online-condoleren\/mevr-martha-verkinderen\/\"},\"author\":{\"name\":\"Evelyne Haerens\",\"@id\":\"https:\/\/www.begrafenissenhaerens.be\/fr\/#\/schema\/person\/f177297c84debaa1138f04bff7a1bb42\"},\"headline\":\"Mevr. Martha Verkinderen\",\"datePublished\":\"2024-06-17T15:18:32+00:00\",\"dateModified\":\"2024-06-17T15:18:32+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/www.begrafenissenhaerens.be\/fr\/online-condoleren\/mevr-martha-verkinderen\/\"},\"wordCount\":19,\"publisher\":{\"@id\":\"https:\/\/www.begrafenissenhaerens.be\/fr\/#organization\"},\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.begrafenissenhaerens.be\/fr\/online-condoleren\/mevr-martha-verkinderen\/\",\"url\":\"https:\/\/www.begrafenissenhaerens.be\/fr\/online-condoleren\/mevr-martha-verkinderen\/\",\"name\":\"Mevr. Martha Verkinderen - HAERENS Sint-Martens-Latem\",\"isPartOf\":{\"@id\":\"https:\/\/www.begrafenissenhaerens.be\/fr\/#website\"},\"datePublished\":\"2024-06-17T15:18:32+00:00\",\"dateModified\":\"2024-06-17T15:18:32+00:00\",\"breadcrumb\":{\"@id\":\"https:\/\/www.begrafenissenhaerens.be\/fr\/online-condoleren\/mevr-martha-verkinderen\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.begrafenissenhaerens.be\/fr\/online-condoleren\/mevr-martha-verkinderen\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.begrafenissenhaerens.be\/fr\/online-condoleren\/mevr-martha-verkinderen\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\/\/www.begrafenissenhaerens.be\/fr\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Mevr. Martha Verkinderen\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.begrafenissenhaerens.be\/fr\/#website\",\"url\":\"https:\/\/www.begrafenissenhaerens.be\/fr\/\",\"name\":\"HAERENS Sint-Martens-Latem\",\"description\":\"Voor een uiterst discrete en stijlvolle aanpak van begrafenissen en crematies bent u bij Haerens uit Sint-Martens-Latem aan het juiste adres.\",\"publisher\":{\"@id\":\"https:\/\/www.begrafenissenhaerens.be\/fr\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.begrafenissenhaerens.be\/fr\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/www.begrafenissenhaerens.be\/fr\/#organization\",\"name\":\"Begrafenissen Haerens\",\"url\":\"https:\/\/www.begrafenissenhaerens.be\/fr\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/www.begrafenissenhaerens.be\/fr\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/www.begrafenissenhaerens.be\/wp-content\/uploads\/2020\/10\/haerens_logo.svg\",\"contentUrl\":\"https:\/\/www.begrafenissenhaerens.be\/wp-content\/uploads\/2020\/10\/haerens_logo.svg\",\"caption\":\"Begrafenissen Haerens\"},\"image\":{\"@id\":\"https:\/\/www.begrafenissenhaerens.be\/fr\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/BegrafenissenHaerens\/\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.begrafenissenhaerens.be\/fr\/#\/schema\/person\/f177297c84debaa1138f04bff7a1bb42\",\"name\":\"Evelyne Haerens\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Mevr. Martha Verkinderen - HAERENS Sint-Martens-Latem","robots":{"index":"noindex","follow":"follow"},"og_locale":"fr_FR","og_type":"article","og_title":"Mevr. Martha Verkinderen - HAERENS Sint-Martens-Latem","og_description":"Geboren te Meulebeke op 26 augustus 1934 en overleden in het WZC \u2018de Lichtervelde\u2019 te Eke op 14 juni 2024.","og_url":"https:\/\/www.begrafenissenhaerens.be\/fr\/online-condoleren\/mevr-martha-verkinderen\/","og_site_name":"HAERENS Sint-Martens-Latem","article_publisher":"https:\/\/www.facebook.com\/BegrafenissenHaerens\/","article_published_time":"2024-06-17T15:18:32+00:00","author":"Evelyne Haerens","twitter_card":"summary_large_image","twitter_misc":{"\u00c9crit par":"Evelyne Haerens","Dur\u00e9e de lecture estim\u00e9e":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.begrafenissenhaerens.be\/fr\/online-condoleren\/mevr-martha-verkinderen\/#article","isPartOf":{"@id":"https:\/\/www.begrafenissenhaerens.be\/fr\/online-condoleren\/mevr-martha-verkinderen\/"},"author":{"name":"Evelyne Haerens","@id":"https:\/\/www.begrafenissenhaerens.be\/fr\/#\/schema\/person\/f177297c84debaa1138f04bff7a1bb42"},"headline":"Mevr. Martha Verkinderen","datePublished":"2024-06-17T15:18:32+00:00","dateModified":"2024-06-17T15:18:32+00:00","mainEntityOfPage":{"@id":"https:\/\/www.begrafenissenhaerens.be\/fr\/online-condoleren\/mevr-martha-verkinderen\/"},"wordCount":19,"publisher":{"@id":"https:\/\/www.begrafenissenhaerens.be\/fr\/#organization"},"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/www.begrafenissenhaerens.be\/fr\/online-condoleren\/mevr-martha-verkinderen\/","url":"https:\/\/www.begrafenissenhaerens.be\/fr\/online-condoleren\/mevr-martha-verkinderen\/","name":"Mevr. Martha Verkinderen - HAERENS Sint-Martens-Latem","isPartOf":{"@id":"https:\/\/www.begrafenissenhaerens.be\/fr\/#website"},"datePublished":"2024-06-17T15:18:32+00:00","dateModified":"2024-06-17T15:18:32+00:00","breadcrumb":{"@id":"https:\/\/www.begrafenissenhaerens.be\/fr\/online-condoleren\/mevr-martha-verkinderen\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.begrafenissenhaerens.be\/fr\/online-condoleren\/mevr-martha-verkinderen\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.begrafenissenhaerens.be\/fr\/online-condoleren\/mevr-martha-verkinderen\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.begrafenissenhaerens.be\/fr\/"},{"@type":"ListItem","position":2,"name":"Mevr. Martha Verkinderen"}]},{"@type":"WebSite","@id":"https:\/\/www.begrafenissenhaerens.be\/fr\/#website","url":"https:\/\/www.begrafenissenhaerens.be\/fr\/","name":"HAERENS Sint-Martens-Latem","description":"Voor een uiterst discrete en stijlvolle aanpak van begrafenissen en crematies bent u bij Haerens uit Sint-Martens-Latem aan het juiste adres.","publisher":{"@id":"https:\/\/www.begrafenissenhaerens.be\/fr\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.begrafenissenhaerens.be\/fr\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/www.begrafenissenhaerens.be\/fr\/#organization","name":"Begrafenissen Haerens","url":"https:\/\/www.begrafenissenhaerens.be\/fr\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/www.begrafenissenhaerens.be\/fr\/#\/schema\/logo\/image\/","url":"https:\/\/www.begrafenissenhaerens.be\/wp-content\/uploads\/2020\/10\/haerens_logo.svg","contentUrl":"https:\/\/www.begrafenissenhaerens.be\/wp-content\/uploads\/2020\/10\/haerens_logo.svg","caption":"Begrafenissen Haerens"},"image":{"@id":"https:\/\/www.begrafenissenhaerens.be\/fr\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/BegrafenissenHaerens\/"]},{"@type":"Person","@id":"https:\/\/www.begrafenissenhaerens.be\/fr\/#\/schema\/person\/f177297c84debaa1138f04bff7a1bb42","name":"Evelyne Haerens"}]}},"_links":{"self":[{"href":"https:\/\/www.begrafenissenhaerens.be\/fr\/wp-json\/wp\/v2\/posts\/12040"}],"collection":[{"href":"https:\/\/www.begrafenissenhaerens.be\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.begrafenissenhaerens.be\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.begrafenissenhaerens.be\/fr\/wp-json\/wp\/v2\/users\/3"}],"replies":[{"embeddable":true,"href":"https:\/\/www.begrafenissenhaerens.be\/fr\/wp-json\/wp\/v2\/comments?post=12040"}],"version-history":[{"count":1,"href":"https:\/\/www.begrafenissenhaerens.be\/fr\/wp-json\/wp\/v2\/posts\/12040\/revisions"}],"predecessor-version":[{"id":12044,"href":"https:\/\/www.begrafenissenhaerens.be\/fr\/wp-json\/wp\/v2\/posts\/12040\/revisions\/12044"}],"wp:attachment":[{"href":"https:\/\/www.begrafenissenhaerens.be\/fr\/wp-json\/wp\/v2\/media?parent=12040"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.begrafenissenhaerens.be\/fr\/wp-json\/wp\/v2\/categories?post=12040"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.begrafenissenhaerens.be\/fr\/wp-json\/wp\/v2\/tags?post=12040"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}